{"id":1506,"count":81,"description":"Il y a toujours un peu de soleil dans les chaussures sign\u00e9es <b>Pons Quintana<\/b>\u2026  Originaire de Menorca, une des \u00eeles Bal\u00e9ares, <b>Pons Quintana<\/b> s\u2019est d\u2019abord fait conna\u00eetre par la qualit\u00e9 et l\u2019allure de ses <b>chaussures tress\u00e9es<\/b> dans une multitude de coloris pour l'\u00e9t\u00e9. Puis pas \u00e0 pas, l'originalit\u00e9 de ses <b>mocassins, derbies, boots et bottes<\/b> pour l'hiver, ainsi que ses talons originaux aux d\u00e9tails raffin\u00e9s ont aussi s\u00e9duit les femmes dans le monde entier.  Depuis trois g\u00e9n\u00e9rations, cette maison familiale <b>Pons Quintana<\/b> met un point d\u2019honneur \u00e0 travailler des mod\u00e8les originaux dans des <b>tr\u00e8s belles mati\u00e8res<\/b>, tout en gardant le cap sur <b>une f\u00e9minit\u00e9 facile \u00e0 porter<\/b>.","link":"https:\/\/www.la-botte.com\/brand\/pons-quintana\/","name":"Pons Quintana","slug":"pons-quintana","taxonomy":"product_brand","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pons Quintana - La Botte Chantilly<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.la-botte.com\/en\/brand\/pons-quintana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Pons Quintana\" \/>\n<meta property=\"og:description\" content=\"Il y a toujours un peu de soleil dans les chaussures sign\u00e9es Pons Quintana\u2026 Originaire de Menorca, une des \u00eeles Bal\u00e9ares, Pons Quintana s\u2019est d\u2019abord fait conna\u00eetre par la qualit\u00e9 et l\u2019allure de ses chaussures tress\u00e9es dans une multitude de coloris pour l&#8217;\u00e9t\u00e9. Puis pas \u00e0 pas, l&#8217;originalit\u00e9 de ses mocassins, derbies, boots et bottes pour l&#8217;hiver, ainsi que ses talons originaux aux d\u00e9tails raffin\u00e9s ont aussi s\u00e9duit les femmes dans le monde entier. Depuis trois g\u00e9n\u00e9rations, cette maison familiale Pons Quintana met un point d\u2019honneur \u00e0 travailler des mod\u00e8les originaux dans des tr\u00e8s belles mati\u00e8res, tout en gardant le cap sur une f\u00e9minit\u00e9 facile \u00e0 porter.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.la-botte.com\/brand\/pons-quintana\/\" \/>\n<meta property=\"og:site_name\" content=\"La Botte Chantilly\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.la-botte.com\\\/brand\\\/pons-quintana\\\/\",\"url\":\"https:\\\/\\\/www.la-botte.com\\\/brand\\\/pons-quintana\\\/\",\"name\":\"Pons Quintana - La Botte Chantilly\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.la-botte.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.la-botte.com\\\/brand\\\/pons-quintana\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.la-botte.com\\\/brand\\\/pons-quintana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.la-botte.com\\\/en\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pons Quintana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.la-botte.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.la-botte.com\\\/en\\\/\",\"name\":\"La Botte Chantilly\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.la-botte.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.la-botte.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.la-botte.com\\\/en\\\/#organization\",\"name\":\"La Botte Chantilly\",\"url\":\"https:\\\/\\\/www.la-botte.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.la-botte.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cdn.promatec.digital\\\/la-botte\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-labotte.png\",\"contentUrl\":\"https:\\\/\\\/cdn.promatec.digital\\\/la-botte\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-labotte.png\",\"width\":600,\"height\":347,\"caption\":\"La Botte Chantilly\"},\"image\":{\"@id\":\"https:\\\/\\\/www.la-botte.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/labottechantilly\",\"http:\\\/\\\/www.instagram.com\\\/labottechantilly\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/la-botte-chantilly\\\/posts\\\/?feedView=all\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pons Quintana - La Botte Chantilly","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.la-botte.com\/en\/brand\/pons-quintana\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Pons Quintana","og_description":"Il y a toujours un peu de soleil dans les chaussures sign\u00e9es Pons Quintana\u2026 Originaire de Menorca, une des \u00eeles Bal\u00e9ares, Pons Quintana s\u2019est d\u2019abord fait conna\u00eetre par la qualit\u00e9 et l\u2019allure de ses chaussures tress\u00e9es dans une multitude de coloris pour l&#8217;\u00e9t\u00e9. Puis pas \u00e0 pas, l&#8217;originalit\u00e9 de ses mocassins, derbies, boots et bottes pour l&#8217;hiver, ainsi que ses talons originaux aux d\u00e9tails raffin\u00e9s ont aussi s\u00e9duit les femmes dans le monde entier. Depuis trois g\u00e9n\u00e9rations, cette maison familiale Pons Quintana met un point d\u2019honneur \u00e0 travailler des mod\u00e8les originaux dans des tr\u00e8s belles mati\u00e8res, tout en gardant le cap sur une f\u00e9minit\u00e9 facile \u00e0 porter.","og_url":"https:\/\/www.la-botte.com\/brand\/pons-quintana\/","og_site_name":"La Botte Chantilly","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.la-botte.com\/brand\/pons-quintana\/","url":"https:\/\/www.la-botte.com\/brand\/pons-quintana\/","name":"Pons Quintana - La Botte Chantilly","isPartOf":{"@id":"https:\/\/www.la-botte.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.la-botte.com\/brand\/pons-quintana\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.la-botte.com\/brand\/pons-quintana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.la-botte.com\/en\/homepage\/"},{"@type":"ListItem","position":2,"name":"Pons Quintana"}]},{"@type":"WebSite","@id":"https:\/\/www.la-botte.com\/en\/#website","url":"https:\/\/www.la-botte.com\/en\/","name":"La Botte Chantilly","description":"","publisher":{"@id":"https:\/\/www.la-botte.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.la-botte.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.la-botte.com\/en\/#organization","name":"La Botte Chantilly","url":"https:\/\/www.la-botte.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.la-botte.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/cdn.promatec.digital\/la-botte\/wp-content\/uploads\/2025\/02\/logo-labotte.png","contentUrl":"https:\/\/cdn.promatec.digital\/la-botte\/wp-content\/uploads\/2025\/02\/logo-labotte.png","width":600,"height":347,"caption":"La Botte Chantilly"},"image":{"@id":"https:\/\/www.la-botte.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/labottechantilly","http:\/\/www.instagram.com\/labottechantilly","https:\/\/www.linkedin.com\/company\/la-botte-chantilly\/posts\/?feedView=all"]}]}},"_links":{"self":[{"href":"https:\/\/www.la-botte.com\/en\/wp-json\/wp\/v2\/product_brand\/1506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.la-botte.com\/en\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/www.la-botte.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"wp:post_type":[{"href":"https:\/\/www.la-botte.com\/en\/wp-json\/wp\/v2\/product?product_brand=1506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}